{"id":312,"count":1,"description":"","link":"https:\/\/www.batteriestar.com\/blog\/tag\/mechrevo-f1\/","name":"Mechrevo F1","slug":"mechrevo-f1","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mechrevo F1 Archives - Battery and Adapter Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.batteriestar.com\/blog\/tag\/mechrevo-f1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mechrevo F1 Archives - Battery and Adapter Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.batteriestar.com\/blog\/tag\/mechrevo-f1\/\" \/>\n<meta property=\"og:site_name\" content=\"Battery and Adapter Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.batteriestar.com\/blog\/tag\/mechrevo-f1\/\",\"url\":\"https:\/\/www.batteriestar.com\/blog\/tag\/mechrevo-f1\/\",\"name\":\"Mechrevo F1 Archives - Battery and Adapter Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.batteriestar.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.batteriestar.com\/blog\/tag\/mechrevo-f1\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.batteriestar.com\/blog\/tag\/mechrevo-f1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.batteriestar.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mechrevo F1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.batteriestar.com\/blog\/#website\",\"url\":\"https:\/\/www.batteriestar.com\/blog\/\",\"name\":\"Battery and Adapter Blog\",\"description\":\"Laptop batteries, Adapters, Chargers, Electronics at the Lowest Prices!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.batteriestar.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mechrevo F1 Archives - Battery and Adapter Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.batteriestar.com\/blog\/tag\/mechrevo-f1\/","og_locale":"en_US","og_type":"article","og_title":"Mechrevo F1 Archives - Battery and Adapter Blog","og_url":"https:\/\/www.batteriestar.com\/blog\/tag\/mechrevo-f1\/","og_site_name":"Battery and Adapter Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.batteriestar.com\/blog\/tag\/mechrevo-f1\/","url":"https:\/\/www.batteriestar.com\/blog\/tag\/mechrevo-f1\/","name":"Mechrevo F1 Archives - Battery and Adapter Blog","isPartOf":{"@id":"https:\/\/www.batteriestar.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.batteriestar.com\/blog\/tag\/mechrevo-f1\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.batteriestar.com\/blog\/tag\/mechrevo-f1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.batteriestar.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Mechrevo F1"}]},{"@type":"WebSite","@id":"https:\/\/www.batteriestar.com\/blog\/#website","url":"https:\/\/www.batteriestar.com\/blog\/","name":"Battery and Adapter Blog","description":"Laptop batteries, Adapters, Chargers, Electronics at the Lowest Prices!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.batteriestar.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.batteriestar.com\/blog\/wp-json\/wp\/v2\/tags\/312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.batteriestar.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.batteriestar.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.batteriestar.com\/blog\/wp-json\/wp\/v2\/posts?tags=312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}